{"id":260,"count":12,"description":"","link":"https:\/\/www.citizensutilityboard.org\/espanol\/category\/rate-hike\/","name":"Rate Hike","slug":"rate-hike","taxonomy":"category","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Rate Hike Archives | CUB Espa\u00f1ol<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Rate Hike Archives | CUB Espa\u00f1ol\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.citizensutilityboard.org\/espanol\/category\/rate-hike\/\" \/>\n<meta property=\"og:site_name\" content=\"CUB Espa\u00f1ol\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.citizensutilityboard.org\/espanol\/wp-content\/uploads\/sites\/2\/2020\/09\/CUB_IL_LogoBadgeRGBAdminLogo.png\" \/>\n\t<meta property=\"og:image:width\" content=\"254\" \/>\n\t<meta property=\"og:image:height\" content=\"254\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@cubespanol\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/www.citizensutilityboard.org\\\/espanol\\\/category\\\/rate-hike\\\/\",\"url\":\"https:\\\/\\\/www.citizensutilityboard.org\\\/espanol\\\/category\\\/rate-hike\\\/\",\"name\":\"Rate Hike Archives | CUB Espa\u00f1ol\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.citizensutilityboard.org\\\/espanol\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.citizensutilityboard.org\\\/espanol\\\/category\\\/rate-hike\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.citizensutilityboard.org\\\/espanol\\\/category\\\/rate-hike\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.citizensutilityboard.org\\\/espanol\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Rate Hike\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.citizensutilityboard.org\\\/espanol\\\/#website\",\"url\":\"https:\\\/\\\/www.citizensutilityboard.org\\\/espanol\\\/\",\"name\":\"CUB Espa\u00f1ol\",\"description\":\"El Citizens Utility Board, CUB, es en Illinois, el grupo de protecci\u00f3n al consumidor en los servicios de gas, electricidad y tel\u00e9fono.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.citizensutilityboard.org\\\/espanol\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.citizensutilityboard.org\\\/espanol\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.citizensutilityboard.org\\\/espanol\\\/#organization\",\"name\":\"Citizens Utility Board\",\"url\":\"https:\\\/\\\/www.citizensutilityboard.org\\\/espanol\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.citizensutilityboard.org\\\/espanol\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.citizensutilityboard.org\\\/espanol\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/09\\\/CUB_IL_LogoBadgeRGBAdminLogo.png\",\"contentUrl\":\"https:\\\/\\\/www.citizensutilityboard.org\\\/espanol\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/09\\\/CUB_IL_LogoBadgeRGBAdminLogo.png\",\"width\":254,\"height\":254,\"caption\":\"Citizens Utility Board\"},\"image\":{\"@id\":\"https:\\\/\\\/www.citizensutilityboard.org\\\/espanol\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/cubespanol\",\"https:\\\/\\\/x.com\\\/cubespanol\",\"https:\\\/\\\/instagram.com\\\/cubillinois\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/CUBIllinois\\\/featured\",\"https:\\\/\\\/twitter.com\\\/cubespanol\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Rate Hike Archives | CUB Espa\u00f1ol","robots":{"index":"noindex","follow":"follow"},"og_locale":"en_US","og_type":"article","og_title":"Rate Hike Archives | CUB Espa\u00f1ol","og_url":"https:\/\/www.citizensutilityboard.org\/espanol\/category\/rate-hike\/","og_site_name":"CUB Espa\u00f1ol","og_image":[{"width":254,"height":254,"url":"https:\/\/www.citizensutilityboard.org\/espanol\/wp-content\/uploads\/sites\/2\/2020\/09\/CUB_IL_LogoBadgeRGBAdminLogo.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_site":"@cubespanol","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.citizensutilityboard.org\/espanol\/category\/rate-hike\/","url":"https:\/\/www.citizensutilityboard.org\/espanol\/category\/rate-hike\/","name":"Rate Hike Archives | CUB Espa\u00f1ol","isPartOf":{"@id":"https:\/\/www.citizensutilityboard.org\/espanol\/#website"},"breadcrumb":{"@id":"https:\/\/www.citizensutilityboard.org\/espanol\/category\/rate-hike\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/www.citizensutilityboard.org\/espanol\/category\/rate-hike\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.citizensutilityboard.org\/espanol\/"},{"@type":"ListItem","position":2,"name":"Rate Hike"}]},{"@type":"WebSite","@id":"https:\/\/www.citizensutilityboard.org\/espanol\/#website","url":"https:\/\/www.citizensutilityboard.org\/espanol\/","name":"CUB Espa\u00f1ol","description":"El Citizens Utility Board, CUB, es en Illinois, el grupo de protecci\u00f3n al consumidor en los servicios de gas, electricidad y tel\u00e9fono.","publisher":{"@id":"https:\/\/www.citizensutilityboard.org\/espanol\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.citizensutilityboard.org\/espanol\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.citizensutilityboard.org\/espanol\/#organization","name":"Citizens Utility Board","url":"https:\/\/www.citizensutilityboard.org\/espanol\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.citizensutilityboard.org\/espanol\/#\/schema\/logo\/image\/","url":"https:\/\/www.citizensutilityboard.org\/espanol\/wp-content\/uploads\/sites\/2\/2020\/09\/CUB_IL_LogoBadgeRGBAdminLogo.png","contentUrl":"https:\/\/www.citizensutilityboard.org\/espanol\/wp-content\/uploads\/sites\/2\/2020\/09\/CUB_IL_LogoBadgeRGBAdminLogo.png","width":254,"height":254,"caption":"Citizens Utility Board"},"image":{"@id":"https:\/\/www.citizensutilityboard.org\/espanol\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/cubespanol","https:\/\/x.com\/cubespanol","https:\/\/instagram.com\/cubillinois","https:\/\/www.youtube.com\/user\/CUBIllinois\/featured","https:\/\/twitter.com\/cubespanol"]}]}},"_links":{"self":[{"href":"https:\/\/www.citizensutilityboard.org\/espanol\/wp-json\/wp\/v2\/categories\/260","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.citizensutilityboard.org\/espanol\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/www.citizensutilityboard.org\/espanol\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/www.citizensutilityboard.org\/espanol\/wp-json\/wp\/v2\/posts?categories=260"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}